{"id":15185,"date":"2023-05-10T09:37:19","date_gmt":"2023-05-10T07:37:19","guid":{"rendered":"https:\/\/www.ou-serrurier.fr\/guide\/?p=15185"},"modified":"2023-11-27T12:45:14","modified_gmt":"2023-11-27T11:45:14","slug":"comment-poser-un-grillage-souple","status":"publish","type":"post","link":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/","title":{"rendered":"Comment poser un grillage souple ?"},"content":{"rendered":"<p>Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions. L\u2019installation d\u2019une cl\u00f4ture grillag\u00e9e permet aussi de cr\u00e9er son espace de vie priv\u00e9e, en limitant la vue mitoyenne. Un grillage correctement install\u00e9, peut servir de support \u00e0 la pose de brise vue, pr\u00e9servant votre intimit\u00e9, particuli\u00e8rement appr\u00e9ci\u00e9e aux beaux jours.<\/p>\n<p>Le grillage est l\u2019une des cl\u00f4tures les plus utilis\u00e9es, la plus simple et la moins co\u00fbteuse \u00e0 installer. En revanche, afin de durer dans le temps et de ne pas s\u2019affaisser \u00e0 la moindre contrainte ,sa requiert quelques \u00e9tapes indispensables. Si vous souhaitez vous lancer, \u00e0 installer vous-m\u00eame votre grillage souple, nous vous expliquons dans cet article\u00a0le faire dans les r\u00e8gles de l\u2019art.<\/p>\n<p>&nbsp;<\/p>\n<h2>Mat\u00e9riel pour la pose d\u2019un grillage<\/h2>\n<p>Penchons-nous tout d\u2019abord sur l\u2019ensemble du mat\u00e9riel n\u00e9cessaire\u00a0\u00e0 la r\u00e9alisation de cette cl\u00f4ture. Sachez qu\u2019il existe d\u00e9sormais des kits complets, avec tous les accessoires fournis pour une longueur donn\u00e9e. Si vous choisissez d\u2019acheter un pack grillage, votre seul souci \u00e0 cette \u00e9tape, sera de conna\u00eetre la longueur du p\u00e9rim\u00e8tre \u00e0 fermer. Si vous souhaitez tout acheter au d\u00e9tail, pr\u00e9voyez donc :<\/p>\n<h3>Le grillage<\/h3>\n<p>Il en existe de diff\u00e9rentes sortes, la nuance r\u00e9side dans l\u2019esth\u00e9tique, mais aussi la solidit\u00e9 et la r\u00e9sistance \u00e0 la corrosion.<\/p>\n<ul>\n<li>Le grillage torsad\u00e9 pr\u00e9sente des mailles crois\u00e9es en forme de losange qui gardent une certaine souplesse. Disponible en simple ou double torsion, ce deuxi\u00e8me \u00e9tant n\u00e9cessairement plus r\u00e9sistant puisque les fils sont torsad\u00e9s par deux fois au lieu d\u2019une.<\/li>\n<li>Le grillage soud\u00e9 forme une structure \u00e0 mailles carr\u00e9es ou rectangulaires. Sa fabrication diff\u00e8re dans le sens ou chaque croisement est soud\u00e9 en usine. Il en r\u00e9sulte un grillage beaucoup plus rigide et statique.<\/li>\n<li>Le grillage rigide, sous forme de panneaux, c\u2019est la cl\u00f4ture la plus rigide et la plus r\u00e9sistante. Ces panneaux grillag\u00e9s se fixent \u00e0 des poteaux sp\u00e9ciaux, et se destinent \u00e0 des terrains relativement plats. La mise en \u0153uvre \u00e9tant l\u00e9g\u00e8rement diff\u00e9rentes, nous n&#8217;aborderons ici que la pose de grillage souple en rouleau.<\/li>\n<\/ul>\n<p>Diff\u00e9rentes mati\u00e8res peuvent \u00eatre utilis\u00e9es dans la conception de grillage. C\u2019est l\u2019\u00e9l\u00e9ment principal justifiant les \u00e9carts de prix, en rapport \u00e0 la solidit\u00e9 et \u00e0 la durabilit\u00e9 du mat\u00e9riaux et de sa protection.<\/p>\n<ul>\n<li>Acier galvanis\u00e9 : c\u2019est le plus courant et le moins cher, toutes les gammes de grillage le proposent.<\/li>\n<\/ul>\n<ul>\n<li>L\u2019inox : il est on\u00e9reux et donc plus rare, mais c\u2019est aussi un mat\u00e9riaux nettement plus solide que l\u2019acier, tr\u00e8s r\u00e9sistant \u00e0 la corrosion notamment.<\/li>\n<li>Le fil plastifi\u00e9 : comme son nom l\u2019indique, le fil est recouvert d\u2019une gaine plastique. Le grillage ainsi constitu\u00e9 \u00e0 l\u2019avantage d&#8217;\u00eatre beaucoup plus esth\u00e9tique, il se d\u00e9cline en de multiples couleurs. La plastification assure en plus une protection suppl\u00e9mentaire au fil, que celui-ci soit de base acier ou inox.<\/li>\n<\/ul>\n<h3>Les poteaux de fixation<\/h3>\n<p>Les poteaux d&#8217;ancrage de grillage sont des profil\u00e9s en forme de T. Ils disposet de trous pr\u00e9vus pour le passage du fil de tension, ainsi que l\u2019installation de jambes de force. Ces axes devront \u00eatre scell\u00e9s dans le sol avec une distance moyenne interm\u00e9diaire de 2m50.<\/p>\n<p>Pour d\u00e9terminer le nombre total de poteaux \u00e0 acheter, divisez votre longueur totale \u00e0 cl\u00f4turer par 2.5, ajoutez 1 si votre r\u00e9sultat n\u2019est pas un nombre entier. Par exemple pour une cl\u00f4ture de 56 m : 56\/2.5 = 22.4 soit 23 poteaux n\u00e9cessaires.<\/p>\n<h3>Les jambes de force<\/h3>\n<p>\u00c0 ne pas n\u00e9gliger ces \u00e9l\u00e9ments transversaux s\u2019ajoutent obligatoirement sur les poteaux aux niveaux des angles. En fonction de la longueur \u00e0 grillager, il est judicieux de renforcer certains poteaux interm\u00e9diaires avec des jambes de force. Ces derni\u00e8res se placent alors dans le m\u00eame axe, tandis qu\u2019elles se disposent \u00e0 90\u00b0 dans le cas de poteaux d\u2019angle.<\/p>\n<p>Ces corni\u00e8res sont importantes, car elles vont venir compenser la traction de la cloture. Celle-ci peut sembler faible avec un simple grillage et par temps calme, mais ajoutez \u00e0 cela un \u00e9ventuel brise vue et du vent, et vous constaterez rapidement la pression \u00e0 laquelle doit r\u00e9sister le grillage. Les jambes de force peuvent mesurer 120 ou 150 cm et se scellent tout comme les poteaux principaux.<\/p>\n<h3>Fil de tension, fil \u00e0 lier et agrafes grillage<\/h3>\n<p>Afin de relier les poteaux entre eux et soutenir le grillage, vous aurez besoin de vous procurer du fil de tension. Celui-ci est galvanis\u00e9 et peut \u00eatre \u00e9galement plastifi\u00e9, afin de correspondre \u00e0 votre type de grillage. Le diam\u00e8tre de ce fil est de 2.4 mm et il est vendu en rouleau de 100 m.<\/p>\n<p>En fonction de la hauteur de votre cl\u00f4ture (et donc de votre grillage), pr\u00e9voyez 2 ou 3 rangs de fils tendus pour assurer un bon maintien. En moyenne, pour une hauteur standard d\u20191m50, il faut 3 rangs, pour que le grillage n\u2019ai pas tendance \u00e0 \u201cbomber\u201d d\u2019un c\u00f4t\u00e9 ou de l\u2019autre.<\/p>\n<p>Le fil \u00e0 lier de diam\u00e8tre 1.6 mm sert lui \u00e0 fixer le grillage sur le fil de tension. Il s\u2019utilise par simple torsade. Pour une fixation plus sophistiqu\u00e9e, vous pouvez choisir d\u2019utiliser des agrafes \u00e0 grillage. Dans ce cas, vous devez aussi vous munir de la pince ad\u00e9quate \u00e0 leur pose.<\/p>\n<h3>Raidisseurs de fil de tension<\/h3>\n<p>Afin de garantir la rigidit\u00e9 parfaite de votre installation. Mais aussi pour pouvoir r\u00e9ajuster la tension au fil du temps, vous devez placer des raidisseurs. Ce petit syst\u00e8me se fixe au poteau d\u2019arriv\u00e9e de ligne, une fois le fil de tension ins\u00e9r\u00e9 dedans, il vous suffit alors de tourner pour tendre le fil au maximum.<\/p>\n<p>Une roue crant\u00e9e permet de bloquer le roulement inverse, le fil reste donc parfaitement tendu. Au fil des ann\u00e9es, une certaine souplesse peut gagner l\u2019ensemble de l\u2019installation, il suffira alors de redonner quelques tours sur le raidisseur pour rigidifier \u00e0 nouveau.<\/p>\n<h3>Les barres de tension de grillage<\/h3>\n<p>Ces tiges se placent verticalement, en les glissant entre les mailles du grillage souple, sur le premier et juste avant le dernier poteau. La barre de tension s\u2019enfonce ensuite dans le sol et permet de maintenir une traction homog\u00e8ne du grillage sur toute sa surface. Ces barres mesurent 2 m pour un diam\u00e8tre de 8 mm.<\/p>\n<p>Vous aurez \u00e9galement besoin de piquets de bois et ficelle, afin de pr\u00e9parer le trac\u00e9 de cl\u00f4ture. Pour la mise en \u0153uvre, pr\u00e9voyez une pince coupante, un marteau massette ainsi qu\u2019une pince plate et un niveau \u00e0 bulle. Afin de creuser les trous de scellement, vous utiliserez une b\u00eache ou un louchet. Il vous faudra aussi de quoi pr\u00e9parer le b\u00e9ton : une auge, une truelle, ciment, sable, gravier et eau.<\/p>\n<h2>Pr\u00e9paration du terrain, scellement des poteaux de grillage<\/h2>\n<p>Avant toute chose, il faut pr\u00e9parer le trac\u00e9 de votre cl\u00f4ture. \u00c0 ce sujet, nous vous conseillons vivement de prendre ces quelques pr\u00e9cautions pr\u00e9alables aux travaux :<\/p>\n<ul>\n<li>Informez-vous aupr\u00e8s de la mairie\u00a0au sujet du Plan Local d\u2019Urbanisme (PLU) qui peut imposer des r\u00e8gles en mati\u00e8re de cl\u00f4ture, il serait donc judicieux de s\u2019assurer que votre projet respecte bien toutes les conditions avant de se lancer.<\/li>\n<\/ul>\n<ul>\n<li>Si vous avez le moindre doute sur les limites exactes de votre parcelle, songez \u00e0 faire une demande de consultation du cadastre. Tout cela vous \u00e9vitera des d\u00e9convenues, tant avec les administrations qu\u2019avec vos voisins.<\/li>\n<\/ul>\n<ul>\n<li>Pensez \u00e9galement \u00e0 avertir le voisinage, de votre intention de travaux sur la ligne de mitoyennet\u00e9. L\u2019accord entre les parties est n\u00e9cessaire et les frais de mise en \u0153uvre de cl\u00f4ture peuvent d\u2019ailleurs \u00eatre partag\u00e9s. Recueillez autant que possible l&#8217;accord \u00e9crit de ces derniers.<\/li>\n<\/ul>\n<p>Lorsque vous avez toutes les autorisations requises, vous pouvez commencer le tra\u00e7age pr\u00e9alable \u00e0 l\u2019installation d\u2019un grillage. Pour ce faire, vous utiliserez des poteaux de bois entre lequel vous tendrez de la ficelle. Vous n\u2019aurez plus qu&#8217;\u00e0 suivre ce balisage t\u00e9moin, qui vous servira de rep\u00e8re et garantira la lin\u00e9arit\u00e9 de l\u2019ouvrage.<\/p>\n<p>Marquez l\u2019emplacement des poteaux interm\u00e9diaires avec des tasseaux plus petits, pour rappel, ceux-ci doivent \u00eatre espac\u00e9 d\u2019environ 2m50. Commencer ensuite \u00e0 creuser les trous\u00a0en d\u00e9caissant un carr\u00e9 de 20 cm sur une profondeur de 30 cm. Utilisez votre ficelle comme rep\u00e8re, sachant que\u00a0le poteau doit avoir une position centrale.<\/p>\n<p>Installez le premier poteau d\u2019angle, en l&#8217;enfon\u00e7ant de 40 cm (en comptant le trou), afin\u00a0que celui-ci surplombe la hauteur du grillage d\u2019environ 5 cm. Veillez \u00e0 la bonne orientation du T, le c\u00f4t\u00e9 plat doit se trouver vers l&#8217;ext\u00e9rieur.\u00a0Faites de m\u00eame avec les poteaux suivant, de sorte que les trous de passage du fil de tension s\u2019alignent parfaitement. Si vous avez un niveau laser, il vous sera d\u2019une grande aide pour r\u00e9aliser cette installation minutieuse. N\u2019oubliez pas de fixer les jambes de force sur les poteaux d\u2019angle, et si n\u00e9cessaire sur les poteaux transversaux (grandes longueur).<\/p>\n<p>Pr\u00e9parez maintenant le b\u00e9ton pour sceller les piquets et la base des jambes de force. Dans une auge, m\u00e9langez 1 volume de ciment, 2 volumes de sable, 3 volumes de graviers et \u00bd volume d\u2019eau. Une fois le b\u00e9ton homog\u00e8ne, verser dans les trous puis exercez des mouvements verticaux \u00e0 la truelle, afin que le m\u00e9lange se r\u00e9partisse bien dans le trou. V\u00e9rifiez la bonne position du poteau et son aplomb \u00e0 l\u2019aide du niveau \u00e0 bulle. Ajustez si besoin, quitte \u00e0 caler avec des pierres le temps du s\u00e9chage. 3 jours minimum seront indispensables \u00e0 la bonne solidification de la structure, avant de pouvoir poursuivre les travaux de cl\u00f4ture.<\/p>\n<h2>Installation du grillage souple<\/h2>\n<p>Maintenant que les poteaux sont bien ancr\u00e9s vous pouvez installer le fil de tension. Amorcez chaque ligne en nouant le fil sur le trou du poteau de d\u00e9part. Utilisez une pince plate afin d\u2019enrouler l&#8217;extr\u00e9mit\u00e9 du fil tout autour de la ligne de tension. R\u00e9p\u00e9tez l\u2019op\u00e9ration sur celui du bas et en fonction de la hauteur sur le fil du milieu.<\/p>\n<p>Tendez vos fils respectifs en les passant dans chaque poteau jusqu\u2019au raidisseur, que vous aurez pr\u00e9alablement fix\u00e9 au poteau d\u2019arriv\u00e9e. Ins\u00e9rez ensuite l&#8217;extr\u00e9mit\u00e9 du fil dans le rouleau \u00e0 cliquet, puis mettez en tension en tournant \u00e0 l\u2019aide d\u2019une cl\u00e9.<\/p>\n<p>Toute la base de votre cl\u00f4ture est pr\u00eate, vous allez d\u00e9sormais pouvoir fixer votre grillage sur ces supports solides. D\u00e9roulez votre rouleau puis glissez la barre de tension verticalement (dessus-dessous) entre les premi\u00e8res mailles. Positionnez l\u2019ensemble \u00e0 l\u2019int\u00e9rieur du T profil\u00e9, puis attachez solidement en trois points, avec du fil \u00e0 lier.<\/p>\n<p>Au niveau du poteau d\u2019arriv\u00e9e, fixez des raidisseurs puis reliez-les \u00e0 une barre de tension, gliss\u00e9e cette fois \u00e0 30 cm du poteau. Cette technique va vous permettre de jouer sur les raidisseurs pour tendre uniform\u00e9ment le grillage sur toute sa hauteur.\u00a0Celui-ci doit donc gagner en rigidit\u00e9 et venir se plaquer naturellement contre vos fils de tension. Il ne vous restera alors plus qu\u2019\u00e0 l\u2019accrocher sur toute la longueur. Utilisez du fil \u00e0 lier ou des agrafes sp\u00e9ciales, en prenant soin d\u2019agripper ensemble la maille du grillage et le fil de tension.<\/p>\n<p>Si vous avez pr\u00e9vu d\u2019installer un brisevue, il ne vous reste plus qu\u2019\u00e0 choisir entre :<\/p>\n<ul>\n<li>Canisses<\/li>\n<li>Haie artificielle<\/li>\n<li>Toile synth\u00e9tique<\/li>\n<li>Lani\u00e8res<\/li>\n<li>Brise vue naturel<\/li>\n<\/ul>\n<p>En fonction du mod\u00e8le de brise vue choisi, l\u2019installation sera l\u00e9g\u00e8rement diff\u00e9rente. Certains se posent par tissage sur les mailles de grillage, d\u2019autres directement avec du fil \u00e0 lier ou encore avec des clips de fixation pour brise vue. Aussi esth\u00e9tique que pratique, le parement de grillage vient apporter la touche finale \u00e0 votre cl\u00f4ture, et vous assure l\u2019intimit\u00e9 de votre jardin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.","footnotes":""},"categories":[1],"tags":[],"class_list":["post-15185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment poser un grillage souple ? - Ou Serrurier<\/title>\n<meta name=\"description\" content=\"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment poser un grillage souple ? - Ou Serrurier\" \/>\n<meta property=\"og:description\" content=\"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/\" \/>\n<meta property=\"og:site_name\" content=\"Ou Serrurier\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-10T07:37:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T11:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"848\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/\",\"url\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/\",\"name\":\"Comment poser un grillage souple ? - Ou Serrurier\",\"isPartOf\":{\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg\",\"datePublished\":\"2023-05-10T07:37:19+00:00\",\"dateModified\":\"2023-11-27T11:45:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/#\/schema\/person\/7adcf2a054a08cc032662e22bc1fbf87\"},\"description\":\"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#primaryimage\",\"url\":\"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg\",\"contentUrl\":\"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg\",\"width\":1280,\"height\":848,\"caption\":\"grillage maison\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ou Serrurier\",\"item\":\"https:\/\/www.ou-serrurier.fr\/guide\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide\",\"item\":\"https:\/\/www.ou-serrurier.fr\/guide\/liste\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment poser un grillage souple ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/#website\",\"url\":\"https:\/\/www.ou-serrurier.fr\/guide\/\",\"name\":\"Ou Serrurier\",\"description\":\"Tout savoir sur la serrurerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ou-serrurier.fr\/guide\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ou-serrurier.fr\/guide\/#\/schema\/person\/7adcf2a054a08cc032662e22bc1fbf87\",\"name\":\"Martin\",\"description\":\"Martin est le r\u00e9dacteur en chef de la section Guide du site Ou-Serrurier.fr ! 15 ans d'exp\u00e9rience dans le monde de la serrurerie.\",\"url\":\"https:\/\/www.ou-serrurier.fr\/guide\/author\/martin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment poser un grillage souple ? - Ou Serrurier","description":"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment poser un grillage souple ? - Ou Serrurier","og_description":"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.","og_url":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/","og_site_name":"Ou Serrurier","article_published_time":"2023-05-10T07:37:19+00:00","article_modified_time":"2023-11-27T11:45:14+00:00","og_image":[{"width":1280,"height":848,"url":"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg","type":"image\/jpeg"}],"author":"Martin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Martin","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/","url":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/","name":"Comment poser un grillage souple ? - Ou Serrurier","isPartOf":{"@id":"https:\/\/www.ou-serrurier.fr\/guide\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#primaryimage"},"image":{"@id":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg","datePublished":"2023-05-10T07:37:19+00:00","dateModified":"2023-11-27T11:45:14+00:00","author":{"@id":"https:\/\/www.ou-serrurier.fr\/guide\/#\/schema\/person\/7adcf2a054a08cc032662e22bc1fbf87"},"description":"Lorsqu\u2019on a un jardin, il est toujours pr\u00e9f\u00e9rable de le cl\u00f4turer enti\u00e8rement. Ceci garantie la s\u00e9curit\u00e9 de vos enfants et animaux, qui ne pourront pas sortir,\u00a0et vous pr\u00e9muni contre les intrusions.","breadcrumb":{"@id":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#primaryimage","url":"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg","contentUrl":"https:\/\/www.ou-serrurier.fr\/guide\/wp-content\/uploads\/2023\/05\/the-fence-g025755fdd-1280.jpg","width":1280,"height":848,"caption":"grillage maison"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ou-serrurier.fr\/guide\/comment-poser-un-grillage-souple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ou Serrurier","item":"https:\/\/www.ou-serrurier.fr\/guide\/"},{"@type":"ListItem","position":2,"name":"Guide","item":"https:\/\/www.ou-serrurier.fr\/guide\/liste\/"},{"@type":"ListItem","position":3,"name":"Comment poser un grillage souple ?"}]},{"@type":"WebSite","@id":"https:\/\/www.ou-serrurier.fr\/guide\/#website","url":"https:\/\/www.ou-serrurier.fr\/guide\/","name":"Ou Serrurier","description":"Tout savoir sur la serrurerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ou-serrurier.fr\/guide\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ou-serrurier.fr\/guide\/#\/schema\/person\/7adcf2a054a08cc032662e22bc1fbf87","name":"Martin","description":"Martin est le r\u00e9dacteur en chef de la section Guide du site Ou-Serrurier.fr ! 15 ans d'exp\u00e9rience dans le monde de la serrurerie.","url":"https:\/\/www.ou-serrurier.fr\/guide\/author\/martin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/posts\/15185"}],"collection":[{"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/comments?post=15185"}],"version-history":[{"count":0,"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/posts\/15185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/media\/15186"}],"wp:attachment":[{"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/media?parent=15185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/categories?post=15185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ou-serrurier.fr\/guide\/wp-json\/wp\/v2\/tags?post=15185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}